{"id":133,"date":"2023-10-04T08:53:13","date_gmt":"2023-10-04T08:53:13","guid":{"rendered":"https:\/\/demo.bosathemes.com\/fse\/agence\/?page_id=13"},"modified":"2025-11-03T14:13:31","modified_gmt":"2025-11-03T14:13:31","slug":"inicio","status":"publish","type":"page","link":"https:\/\/mederos-netzband.com\/de\/","title":{"rendered":"HOME"},"content":{"rendered":"<div class=\"wp-block-uagb-container uagb-block-b62c5dc5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-d2b54a4e\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-166373bc\">\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-advanced-heading uagb-block-a9ef6cf7\"><h1 class=\"uagb-heading-text\">WILLKOMMEN BEI DER L\u00d6SUNG!<\/h1><\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-advanced-heading uagb-block-98cb72cc\"><h1 class=\"uagb-heading-text\">Die \u00fcber 25-j\u00e4hrige Erfahrung unseres Anwaltsteams ist Ihr Vorteil<\/h1><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-9acd44af\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-8dca2ec3 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/mederos-netzband.com\/de\/inicio\/sobre-nosotros\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">\u00dcBER UNS<\/div><\/a><\/div><\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-544e25f5 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/mederos-netzband.com\/de\/despacho\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">WO WIR SIND<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-modal uagb-block-c4f31320 uagb-modal-wrapper\" data-escpress=\"enable\" data-overlayclick=\"disable\"><div class=\"uagb-spectra-button-wrapper wp-block-button\"><a class=\"uagb-modal-button-link wp-block-button__link uagb-modal-trigger\" href=\"#\" onclick=\"return false;\" target=\"_self\" rel=\"noopener noreferrer\"><span class=\"uagb-modal-content-wrapper\"><span class=\"uagb-inline-editing\">INFORMATION<\/span><\/span><\/a><\/div><div class=\"uagb-effect-default uagb-modal-popup uagb-block-c4f31320 uagb-modal-type-undefined\"><div class=\"uagb-modal-popup-wrap\"><div class=\"uagb-modal-popup-content\">\n<div class=\"wp-block-uagb-info-box uagb-block-b17986a5 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">ZEITPLAN<\/h4><\/div><p class=\"uagb-ifb-desc\"><strong>MONTAG BIS FREITAG<br>9:00 A 14:00<\/strong><\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-50683df9 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">TELEFON<\/h4><\/div><p class=\"uagb-ifb-desc\"><strong>(+34) 928 768 280<br>(+34) 669 859 007<br>(+34) 629 079 765<\/strong><\/p><\/div><\/div>\n<\/div><button class=\"uagb-modal-popup-close\" aria-label=\"Close Modal\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6903bd98\"><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-20dc1a43 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-237d1704\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-5998cfc0\"><h3 class=\"uagb-heading-text\"><mark class=\"uagb-highlight\">DIENSTLEISTUNGEN <\/mark>SPEZIALISIERT F\u00dcR SIE<\/h3><\/div>\n\n\n\n<p class=\"has-accent-text-color has-text-color has-small-font-size\">Lokales B\u00fcro, das international arbeitet.<\/p>\n\n\n\n<div class=\"wp-block-uagb-icon-list uagb-block-16267cb7\"><div class=\"uagb-icon-list__wrap\">\n<div class=\"wp-block-uagb-icon-list-child uagb-block-c8795e44\"><span class=\"uagb-icon-list__label\">\u201eManche Leute m\u00f6gen keine Anw\u00e4lte, bis sie sie brauchen.\u201c Kenneth G. Eade<\/span><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-bcdc3e05 default uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-2e85d044\">\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-a59a0183\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-b368b98f wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/mederos-netzband.com\/de\/contacto\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">KONTAKT<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uagb-block-84d63d92\">\n<div class=\"wp-block-uagb-container uagb-block-3d921031\">\n<div class=\"wp-block-uagb-info-box uagb-block-488b9880 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path d=\"M535 7.03C544.4-2.343 559.6-2.343 568.1 7.029L632.1 71.02C637.5 75.52 640 81.63 640 87.99C640 94.36 637.5 100.5 632.1 104.1L568.1 168.1C559.6 178.3 544.4 178.3 535 168.1C525.7 159.6 525.7 144.4 535 135L558.1 111.1L384 111.1C370.7 111.1 360 101.2 360 87.99C360 74.74 370.7 63.99 384 63.99L558.1 63.1L535 40.97C525.7 31.6 525.7 16.4 535 7.03V7.03zM104.1 376.1L81.94 400L255.1 399.1C269.3 399.1 279.1 410.7 279.1 423.1C279.1 437.2 269.3 447.1 255.1 447.1L81.95 448L104.1 471C114.3 480.4 114.3 495.6 104.1 504.1C95.6 514.3 80.4 514.3 71.03 504.1L7.029 440.1C2.528 436.5-.0003 430.4 0 423.1C0 417.6 2.529 411.5 7.03 407L71.03 343C80.4 333.7 95.6 333.7 104.1 343C114.3 352.4 114.3 367.6 104.1 376.1H104.1zM95.1 64H337.9C334.1 71.18 332 79.34 332 87.1C332 116.7 355.3 139.1 384 139.1L481.1 139.1C484.4 157.5 494.9 172.5 509.4 181.9C511.1 184.3 513.1 186.6 515.2 188.8C535.5 209.1 568.5 209.1 588.8 188.8L608 169.5V384C608 419.3 579.3 448 544 448H302.1C305.9 440.8 307.1 432.7 307.1 423.1C307.1 395.3 284.7 371.1 255.1 371.1L158.9 372C155.5 354.5 145.1 339.5 130.6 330.1C128.9 327.7 126.9 325.4 124.8 323.2C104.5 302.9 71.54 302.9 51.23 323.2L31.1 342.5V128C31.1 92.65 60.65 64 95.1 64V64zM95.1 192C131.3 192 159.1 163.3 159.1 128H95.1V192zM544 384V320C508.7 320 480 348.7 480 384H544zM319.1 352C373 352 416 309 416 256C416 202.1 373 160 319.1 160C266.1 160 223.1 202.1 223.1 256C223.1 309 266.1 352 319.1 352z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Nachlass<\/h5><\/div><div class=\"uagb-ifb-button-wrapper wp-block-button\"><a href=\"https:\/\/mederos-netzband.com\/de\/servicios\/herencia\/\" class=\"uagb-infobox-cta-link wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\" onclick=\"return true;\"><span class=\"uagb-inline-editing\">Read More<\/span><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M504.3 273.6l-112.1 104c-6.992 6.484-17.18 8.218-25.94 4.406c-8.758-3.812-14.42-12.45-14.42-21.1L351.9 288H32C14.33 288 .0002 273.7 .0002 255.1S14.33 224 32 224h319.9l0-72c0-9.547 5.66-18.19 14.42-22c8.754-3.809 18.95-2.075 25.94 4.41l112.1 104C514.6 247.9 514.6 264.1 504.3 273.6z\"><\/path><\/svg><\/a><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-56519db2\">\n<div class=\"wp-block-uagb-info-box uagb-block-4734acdf uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path d=\"M176 240H128v32h48C184.9 272 192 264.9 192 256S184.9 240 176 240zM256 0v128h128L256 0zM224 128L224 0H48C21.49 0 0 21.49 0 48v416C0 490.5 21.49 512 48 512h288c26.51 0 48-21.49 48-48V160h-127.1C238.3 160 224 145.7 224 128zM292.5 315.5l11.38 11.25c6.25 6.25 6.25 16.38 0 22.62l-29.88 30L304 409.4c6.25 6.25 6.25 16.38 0 22.62l-11.25 11.38c-6.25 6.25-16.5 6.25-22.75 0L240 413.3l-30 30c-6.249 6.25-16.48 6.266-22.73 .0156L176 432c-6.25-6.25-6.25-16.38 0-22.62l29.1-30.12L146.8 320H128l.0078 48.01c0 8.875-7.125 16-16 16L96 384c-8.875 0-16-7.125-16-16v-160C80 199.1 87.13 192 96 192h80c35.38 0 64 28.62 64 64c0 24.25-13.62 45-33.5 55.88L240 345.4l29.88-29.88C276.1 309.3 286.3 309.3 292.5 315.5z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Anspr\u00fcche<\/h5><\/div><div class=\"uagb-ifb-button-wrapper wp-block-button\"><a href=\"https:\/\/mederos-netzband.com\/de\/servicios\/reclamaciones\/\" class=\"uagb-infobox-cta-link wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\" onclick=\"return true;\"><span class=\"uagb-inline-editing\">Read More<\/span><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M504.3 273.6l-112.1 104c-6.992 6.484-17.18 8.218-25.94 4.406c-8.758-3.812-14.42-12.45-14.42-21.1L351.9 288H32C14.33 288 .0002 273.7 .0002 255.1S14.33 224 32 224h319.9l0-72c0-9.547 5.66-18.19 14.42-22c8.754-3.809 18.95-2.075 25.94 4.41l112.1 104C514.6 247.9 514.6 264.1 504.3 273.6z\"><\/path><\/svg><\/a><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-31b9cbc5\">\n<div class=\"wp-block-uagb-info-box uagb-block-28e0080b uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M240.1 4.216C249.1-1.405 262-1.405 271.9 4.216L443.6 102.4L447.1 104V104.9L495.9 132.2C508.5 139.4 514.6 154.2 510.9 168.2C507.2 182.2 494.5 192 479.1 192H31.1C17.49 192 4.795 182.2 1.071 168.2C-2.653 154.2 3.524 139.4 16.12 132.2L63.1 104.9V104L68.37 102.4L240.1 4.216zM64 224H128V416H168V224H232V416H280V224H344V416H384V224H448V420.3C448.6 420.6 449.2 420.1 449.8 421.4L497.8 453.4C509.5 461.2 514.7 475.8 510.6 489.3C506.5 502.8 494.1 512 480 512H32C17.9 512 5.46 502.8 1.373 489.3C-2.713 475.8 2.517 461.2 14.25 453.4L62.25 421.4C62.82 420.1 63.41 420.6 64 420.3V224z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title\">Internationales Recht<\/h6><\/div><div class=\"uagb-ifb-button-wrapper wp-block-button\"><a href=\"https:\/\/mederos-netzband.com\/de\/servicios\/derecho-internacional-aleman\/\" class=\"uagb-infobox-cta-link wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\" onclick=\"return true;\"><span class=\"uagb-inline-editing\">Read More<\/span><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M504.3 273.6l-112.1 104c-6.992 6.484-17.18 8.218-25.94 4.406c-8.758-3.812-14.42-12.45-14.42-21.1L351.9 288H32C14.33 288 .0002 273.7 .0002 255.1S14.33 224 32 224h319.9l0-72c0-9.547 5.66-18.19 14.42-22c8.754-3.809 18.95-2.075 25.94 4.41l112.1 104C514.6 247.9 514.6 264.1 504.3 273.6z\"><\/path><\/svg><\/a><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uagb-block-502620cb\">\n<div class=\"wp-block-uagb-container uagb-block-9931ad6d\">\n<div class=\"wp-block-uagb-info-box uagb-block-d5a431be uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path d=\"M256 0v128h128L256 0zM224 128L224 0H48C21.49 0 0 21.49 0 48v416C0 490.5 21.49 512 48 512h288c26.51 0 48-21.49 48-48V160h-127.1C238.3 160 224 145.7 224 128zM64 72C64 67.63 67.63 64 72 64h80C156.4 64 160 67.63 160 72v16C160 92.38 156.4 96 152 96h-80C67.63 96 64 92.38 64 88V72zM64 136C64 131.6 67.63 128 72 128h80C156.4 128 160 131.6 160 136v16C160 156.4 156.4 160 152 160h-80C67.63 160 64 156.4 64 152V136zM304 384c8.875 0 16 7.125 16 16S312.9 416 304 416h-47.25c-16.38 0-31.25-9.125-38.63-23.88c-2.875-5.875-8-6.5-10.12-6.5s-7.25 .625-10 6.125l-7.75 15.38C187.6 412.6 181.1 416 176 416H174.9c-6.5-.5-12-4.75-14-11L144 354.6L133.4 386.5C127.5 404.1 111 416 92.38 416H80C71.13 416 64 408.9 64 400S71.13 384 80 384h12.38c4.875 0 9.125-3.125 10.62-7.625l18.25-54.63C124.5 311.9 133.6 305.3 144 305.3s19.5 6.625 22.75 16.5l13.88 41.63c19.75-16.25 54.13-9.75 66 14.12c2 4 6 6.5 10.12 6.5H304z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Vertrag<\/h5><\/div><div class=\"uagb-ifb-button-wrapper wp-block-button\"><a href=\"https:\/\/mederos-netzband.com\/de\/servicios\/contrato\/\" class=\"uagb-infobox-cta-link wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\" onclick=\"return true;\"><span class=\"uagb-inline-editing\">Read More<\/span><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M504.3 273.6l-112.1 104c-6.992 6.484-17.18 8.218-25.94 4.406c-8.758-3.812-14.42-12.45-14.42-21.1L351.9 288H32C14.33 288 .0002 273.7 .0002 255.1S14.33 224 32 224h319.9l0-72c0-9.547 5.66-18.19 14.42-22c8.754-3.809 18.95-2.075 25.94 4.41l112.1 104C514.6 247.9 514.6 264.1 504.3 273.6z\"><\/path><\/svg><\/a><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-a7c6a099\">\n<div class=\"wp-block-uagb-info-box uagb-block-49724666 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M445.1 338.6l-14.77-32C425.1 295.3 413.7 288 401.2 288H46.76C34.28 288 22.94 295.3 17.7 306.6l-14.77 32c-4.563 9.906-3.766 21.47 2.109 30.66S21.09 384 31.1 384l.001 112c0 8.836 7.164 16 16 16h32c8.838 0 16-7.164 16-16V384h256v112c0 8.836 7.164 16 16 16h31.1c8.838 0 16-7.164 16-16L416 384c10.91 0 21.08-5.562 26.95-14.75S449.6 348.5 445.1 338.6zM111.1 128c0-29.48 16.2-54.1 40-68.87L151.1 256h48l.0092-208h48L247.1 256h48l.0093-196.9C319.8 73 335.1 98.52 335.1 128l-.0094 128h48.03l-.0123-128c0-70.69-57.31-128-128-128H191.1C121.3 0 63.98 57.31 63.98 128l.0158 128h47.97L111.1 128z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Anwesen<\/h5><\/div><div class=\"uagb-ifb-button-wrapper wp-block-button\"><a href=\"https:\/\/mederos-netzband.com\/de\/servicios\/inmuebles\/\" class=\"uagb-infobox-cta-link wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\" onclick=\"return true;\"><span class=\"uagb-inline-editing\">Read More<\/span><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M504.3 273.6l-112.1 104c-6.992 6.484-17.18 8.218-25.94 4.406c-8.758-3.812-14.42-12.45-14.42-21.1L351.9 288H32C14.33 288 .0002 273.7 .0002 255.1S14.33 224 32 224h319.9l0-72c0-9.547 5.66-18.19 14.42-22c8.754-3.809 18.95-2.075 25.94 4.41l112.1 104C514.6 247.9 514.6 264.1 504.3 273.6z\"><\/path><\/svg><\/a><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-20b9f0c5\">\n<div class=\"wp-block-uagb-info-box uagb-block-40114e69 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path d=\"M184 88C184 118.9 158.9 144 128 144C97.07 144 72 118.9 72 88C72 57.07 97.07 32 128 32C158.9 32 184 57.07 184 88zM208.4 196.3C178.7 222.7 160 261.2 160 304C160 338.3 171.1 369.8 192 394.5V416C192 433.7 177.7 448 160 448H96C78.33 448 64 433.7 64 416V389.2C26.16 371.2 0 332.7 0 288C0 226.1 50.14 176 112 176H144C167.1 176 190.2 183.5 208.4 196.3V196.3zM64 245.7C54.04 256.9 48 271.8 48 288C48 304.2 54.04 319.1 64 330.3V245.7zM448 416V394.5C468 369.8 480 338.3 480 304C480 261.2 461.3 222.7 431.6 196.3C449.8 183.5 472 176 496 176H528C589.9 176 640 226.1 640 288C640 332.7 613.8 371.2 576 389.2V416C576 433.7 561.7 448 544 448H480C462.3 448 448 433.7 448 416zM576 330.3C585.1 319.1 592 304.2 592 288C592 271.8 585.1 256.9 576 245.7V330.3zM568 88C568 118.9 542.9 144 512 144C481.1 144 456 118.9 456 88C456 57.07 481.1 32 512 32C542.9 32 568 57.07 568 88zM256 96C256 60.65 284.7 32 320 32C355.3 32 384 60.65 384 96C384 131.3 355.3 160 320 160C284.7 160 256 131.3 256 96zM448 304C448 348.7 421.8 387.2 384 405.2V448C384 465.7 369.7 480 352 480H288C270.3 480 256 465.7 256 448V405.2C218.2 387.2 192 348.7 192 304C192 242.1 242.1 192 304 192H336C397.9 192 448 242.1 448 304zM256 346.3V261.7C246 272.9 240 287.8 240 304C240 320.2 246 335.1 256 346.3zM384 261.7V346.3C393.1 335 400 320.2 400 304C400 287.8 393.1 272.9 384 261.7z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title\">Familie<\/h5><\/div><div class=\"uagb-ifb-button-wrapper wp-block-button\"><a href=\"https:\/\/mederos-netzband.com\/de\/servicios\/familia\/\" class=\"uagb-infobox-cta-link wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\" onclick=\"return true;\"><span class=\"uagb-inline-editing\">Read More<\/span><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M504.3 273.6l-112.1 104c-6.992 6.484-17.18 8.218-25.94 4.406c-8.758-3.812-14.42-12.45-14.42-21.1L351.9 288H32C14.33 288 .0002 273.7 .0002 255.1S14.33 224 32 224h319.9l0-72c0-9.547 5.66-18.19 14.42-22c8.754-3.809 18.95-2.075 25.94 4.41l112.1 104C514.6 247.9 514.6 264.1 504.3 273.6z\"><\/path><\/svg><\/a><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-42051952 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div data-aos= \"fade-right\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uagb-block-c0ad021c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-b40235d2\">\n<div class=\"wp-block-uagb-info-box uagb-block-b323e4b3 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M511.2 387l-23.25 100.8c-3.266 14.25-15.79 24.22-30.46 24.22C205.2 512 0 306.8 0 54.5c0-14.66 9.969-27.2 24.22-30.45l100.8-23.25C139.7-2.602 154.7 5.018 160.8 18.92l46.52 108.5c5.438 12.78 1.77 27.67-8.98 36.45L144.5 207.1c33.98 69.22 90.26 125.5 159.5 159.5l44.08-53.8c8.688-10.78 23.69-14.51 36.47-8.975l108.5 46.51C506.1 357.2 514.6 372.4 511.2 387z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title\">OBT\u00c9N UNA CONSULTA<\/h6><\/div><p class=\"uagb-ifb-desc\"><strong>928 768 280<\/strong><\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-d43b0052\">\n<p class=\"has-text-align-left has-accent-text-color has-text-color has-small-font-size\">Ben\u00f6tigen Sie Rechtsberatung von Anw\u00e4lten auf Spanisch oder Deutsch?<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-2f15e8af\">\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-e12c7df1\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-a2197062 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/mederos-netzband.com\/de\/contact\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">EINEN TERMIN MACHEN<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-80acdf4c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-1c068a5b\">\n<div class=\"wp-block-uagb-container uagb-block-9d49cd3d default uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-3318871f default uagb-is-root-container\">\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n      \n\t\t\t<div class=\"uagb-icon-wrapper uagb-block-1662e8a5  wp-block-uagb-icon--has-margin\"\n\t\t\tstyle=\"\" >\n\t\t\t\t\t\t\t\t<div class='uagb-icon-margin-wrapper'>\n\t\t\t\t\t\t\t\t\t<span class=\"uagb-svg-wrapper\" \n\t\t\t\t\t aria-label=\"play\"\t\t\t\t\ttabindex=\"0\">\t\t\n\t\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer\" href=\"#\" target=\"_blank\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 384 512\" role=\"graphics-symbol\" aria-hidden=\"false\" aria-label=\"\"><path d=\"M361 215C375.3 223.8 384 239.3 384 256C384 272.7 375.3 288.2 361 296.1L73.03 472.1C58.21 482 39.66 482.4 24.52 473.9C9.377 465.4 0 449.4 0 432V80C0 62.64 9.377 46.63 24.52 38.13C39.66 29.64 58.21 29.99 73.03 39.04L361 215z\"><\/path><\/svg><\/a>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-eaa31454\">\n<figure class=\"wp-block-image size-full has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4174-scaled.jpg\" alt=\"\" class=\"wp-image-533\" style=\"border-radius:30px\" srcset=\"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4174-scaled.jpg 2560w, https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4174-300x225.jpg 300w, https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4174-1024x768.jpg 1024w, https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4174-768x576.jpg 768w, https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4174-1536x1152.jpg 1536w, https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4174-2048x1536.jpg 2048w, https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4174-16x12.jpg 16w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-e674bc3a wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4175-1024x768.jpg ,https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4175-scaled.jpg 780w, https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4175-scaled.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4175-1024x768.jpg\" alt=\"\" class=\"uag-image-534\" width=\"1024\" height=\"683\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5c6c6a4e\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-b423c1bd\"><h3 class=\"uagb-heading-text\"><strong><mark class=\"uagb-highlight\">DIE PHILOSOPHIE<\/mark> AUS UNSEREM B\u00dcR<\/strong>O<\/h3><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-7a262c4d default uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-9a6e60fb\">\n<div class=\"wp-block-uagb-icon-list uagb-block-2942ec1c\"><div class=\"uagb-icon-list__wrap\">\n<div class=\"wp-block-uagb-icon-list-child uagb-block-66796b9e\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">Die Grundlage unserer Kanzlei liegt in der Suche nach der besten Verteidigung f\u00fcr unsere Mandanten.<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-eba72c6b\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">Das Prinzip unserer Arbeit ist Teamarbeit.<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-6c30c97c\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">Es werden immer zwei Anw\u00e4lte zusammenarbeiten.<\/span><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div data-aos= \"fade-left\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uagb-block-76e449c5\">\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"margin-top:0;margin-bottom:0;font-style:normal;font-weight:700\">+25<\/h2>\n\n\n\n<h6 class=\"wp-block-heading has-text-align-center\" style=\"margin-top:0;margin-bottom:0\">A\u00d1OS<\/h6>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-7fb04749\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-aa2f0a18 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/mederos-netzband.com\/de\/sobre-nosotros\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">MEHR \u00dcBER UNS<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e3fbc00c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div data-aos= \"fade-right\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-advanced-heading uagb-block-d74afe1a\"><h3 class=\"uagb-heading-text\">GERICHTLICHER ERFOLG<\/h3><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-36df4bf0 default uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-a73faa86\">\n<div class=\"wp-block-uagb-counter uagb-block-3d1f555b wp-block-uagb-counter--circle\"><div class=\"wp-block-uagb-counter-circle-container\"><div class=\"wp-block-uagb-counter-circle-container__content\"><div class=\"wp-block-uagb-counter__number\"><span class=\"uagb-counter-block-number\" data-duration=\"1.5\" data-to-value=\"96\" data-from-value=\"0\" data-delimiter=\",\"><\/span><span class=\"uagb-counter-block-suffix\">%<\/span><\/div><div class=\"wp-block-uagb-counter__title\"><\/div><\/div><svg preserveaspectratio=\"xMinYMin meet\" viewbox=\"0 0 130 130\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><circle class=\"uagb-counter-circle__background\"><\/circle><circle class=\"uagb-counter-circle__progress\"><\/circle><\/svg><\/div><\/div>\n\n\n\n<h5 class=\"wp-block-heading has-text-align-center has-accent-text-color has-text-color\" style=\"margin-top:0;margin-bottom:0\">Gerichtlich<\/h5>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-06482e49\">\n<div class=\"wp-block-uagb-counter uagb-block-361ec5fb wp-block-uagb-counter--circle\"><div class=\"wp-block-uagb-counter-circle-container\"><div class=\"wp-block-uagb-counter-circle-container__content\"><div class=\"wp-block-uagb-counter__number\"><span class=\"uagb-counter-block-number\" data-duration=\"1.5\" data-to-value=\"90\" data-from-value=\"0\" data-delimiter=\",\"><\/span><span class=\"uagb-counter-block-suffix\">%<\/span><\/div><div class=\"wp-block-uagb-counter__title\"><\/div><\/div><svg preserveaspectratio=\"xMinYMin meet\" viewbox=\"0 0 130 130\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><circle class=\"uagb-counter-circle__background\"><\/circle><circle class=\"uagb-counter-circle__progress\"><\/circle><\/svg><\/div><\/div>\n\n\n\n<h5 class=\"wp-block-heading has-text-align-center has-accent-text-color has-text-color\" style=\"margin-top:0;margin-bottom:0\">Au\u00dfergerichtlich<\/h5>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f20a9309 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-ae1668a8\">\n<div data-aos= \"fade-left\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-advanced-heading uagb-block-675ac6ce\"><h3 class=\"uagb-heading-text translation-block\">Gr\u00fcndungspartner<\/h3><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-216b198f default uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-088c9bd9\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a0484af3ba82&quot;}\" data-wp-interactive=\"core\/image\" class=\"wp-block-image size-full is-resized has-custom-border wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-on-async--load=\"callbacks.setButtonStyles\" data-wp-on-async-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2024\/02\/wolfran.jpeg\" alt=\"\" class=\"wp-image-754\" style=\"border-top-left-radius:30px;border-top-right-radius:30px;width:375px;height:auto\" srcset=\"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2024\/02\/wolfran.jpeg 800w, https:\/\/mederos-netzband.com\/wp-content\/uploads\/2024\/02\/wolfran-300x300.jpeg 300w, https:\/\/mederos-netzband.com\/wp-content\/uploads\/2024\/02\/wolfran-150x150.jpeg 150w, https:\/\/mederos-netzband.com\/wp-content\/uploads\/2024\/02\/wolfran-768x768.jpeg 768w, https:\/\/mederos-netzband.com\/wp-content\/uploads\/2024\/02\/wolfran-12x12.jpeg 12w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Vergr\u00f6\u00dfern\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on-async--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-4047251e alignwide uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-c80761e8\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-663a94ef\"><h5 class=\"uagb-heading-text\"><strong>WOLFRAM&nbsp;&nbsp;NETZBAND<\/strong><\/h5><p class=\"uagb-desc-text\">GR\u00dcNDUNGSPARTNER<\/p><\/div>\n\n\n\n<p class=\"has-text-align-center has-accent-text-color has-text-color has-link-color has-x-small-font-size wp-elements-cf8723e6215b184773a4acfe18828a49\">Rechtsanwalt<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-5cf9920e\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-6c0f370c wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/mederos-netzband.com\/de\/wolfram-armin-netzband\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Mehr lesen<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-04737b9a\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a0484af3cad7&quot;}\" data-wp-interactive=\"core\/image\" class=\"wp-block-image size-full has-custom-border wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-on-async--load=\"callbacks.setButtonStyles\" data-wp-on-async-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2024\/01\/Imagen-de-WhatsApp-2024-01-11-a-las-10.10.30_0600dd0d.jpg\" alt=\"\" class=\"wp-image-751\" style=\"border-top-left-radius:30px;border-top-right-radius:30px;aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2024\/01\/Imagen-de-WhatsApp-2024-01-11-a-las-10.10.30_0600dd0d.jpg 768w, https:\/\/mederos-netzband.com\/wp-content\/uploads\/2024\/01\/Imagen-de-WhatsApp-2024-01-11-a-las-10.10.30_0600dd0d-225x300.jpg 225w, https:\/\/mederos-netzband.com\/wp-content\/uploads\/2024\/01\/Imagen-de-WhatsApp-2024-01-11-a-las-10.10.30_0600dd0d-9x12.jpg 9w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Vergr\u00f6\u00dfern\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on-async--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-69231481 alignwide uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-f821d3ea\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8748e763\"><h6 class=\"uagb-heading-text\"><strong>ELSA MEDEROS FERNANDES<\/strong><\/h6><p class=\"uagb-desc-text\">GR\u00dcNDUNGSPARTNER<\/p><\/div>\n\n\n\n<p class=\"has-text-align-center has-accent-text-color has-text-color has-link-color has-x-small-font-size wp-elements-47c4db1ea090ce54ab74ecafa93fcc22\">Rechtsanwalt<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-4db0854d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-5fa154cf wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/mederos-netzband.com\/de\/elsa-mederos-fernandes\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Mehr lesen<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f1f92854 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-67285e5c\"><h3 class=\"uagb-heading-text\"><mark class=\"uagb-highlight\">Rezensionen<\/mark><mark class=\"uagb-highlight\"> <\/mark>von Kunden<\/h3><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-04a71682 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-9e631615\">\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-4e6072ba\">\n<p class=\"has-accent-text-color has-text-color has-small-font-size\" style=\"padding-bottom:var(--wp--preset--spacing--xx-small)\">\u00abEmpfehlenswert, gute Behandlung und sehr professionell.\u00bb<\/p>\n\n\n\n<div class=\"wp-block-group is-content-justification-space-between is-nowrap is-layout-flex wp-container-core-group-is-layout-9d9be7c9 wp-block-group-is-layout-flex\" style=\"border-top-color:#e4e6eb12;border-top-width:1px;padding-top:var(--wp--preset--spacing--small)\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-43394beb\"><h6 class=\"uagb-heading-text\">Aisha<\/h6><p class=\"uagb-desc-text\">Kunde<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-star-rating uagb-block-0b920f0e\"><div class=\"uag-star-rating\" title=\"5\/5\"><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-357bdd33\">\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-54678be8\">\n<p class=\"has-text-color has-small-font-size\" style=\"color:#12121200;padding-bottom:var(--wp--preset--spacing--xx-small)\">\u00abSofortige Aufmerksamkeit, hervorragende Behandlung und wirksame L\u00f6sung.\u00bb<\/p>\n\n\n\n<div class=\"wp-block-group is-content-justification-space-between is-nowrap is-layout-flex wp-container-core-group-is-layout-9d9be7c9 wp-block-group-is-layout-flex\" style=\"border-top-color:#e4e6eb12;border-top-width:1px;padding-top:var(--wp--preset--spacing--small)\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3b7a589a\"><h6 class=\"uagb-heading-text\">LEED Music<\/h6><p class=\"uagb-desc-text\">Kunde<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-star-rating uagb-block-1ec18d59\"><div class=\"uag-star-rating\" title=\"5\/5\"><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-cb9bd4be\">\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-ac00f55a\">\n<p class=\"has-accent-text-color has-text-color has-small-font-size\" style=\"padding-bottom:var(--wp--preset--spacing--xx-small)\">\u00abSofortige Aufmerksamkeit, hervorragende Behandlung und wirksame L\u00f6sung.\u00bb<\/p>\n\n\n\n<div class=\"wp-block-group is-content-justification-space-between is-nowrap is-layout-flex wp-container-core-group-is-layout-9d9be7c9 wp-block-group-is-layout-flex\" style=\"border-top-color:#e4e6eb12;border-top-width:1px;padding-top:var(--wp--preset--spacing--small)\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-212c19c8\"><h6 class=\"uagb-heading-text\">Iv\u00e1n Falc\u00f3n<\/h6><p class=\"uagb-desc-text\">Kunde<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-star-rating uagb-block-30d636ed\"><div class=\"uag-star-rating\" title=\"5\/5\"><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-d53cf06d alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-bb263e33 wp-block-group-is-layout-constrained\" style=\"border-radius:30px;min-height:0px;margin-top:var(--wp--preset--spacing--small);margin-bottom:var(--wp--preset--spacing--small);padding-bottom:var(--wp--preset--spacing--xx-small)\">\n<p class=\"has-text-align-center has-custom-color-1-color has-text-color has-link-color has-x-large-font-size wp-elements-0da9215f50111232ac07bea753e81cc9\"><strong>Fordern Sie eine Videokonferenzanfrage an<\/strong><\/p>\n\n\n\n\n\n<p class=\"has-text-align-center has-secondary-color has-text-color has-link-color has-x-small-font-size wp-elements-37398ead546b92ccd4392f32e544207c\">Hiermit erkl\u00e4re ich mein Einverst\u00e4ndnis zur Verarbeitung meiner Daten. Die Daten sind zur Bearbeitung meiner Kontaktanfrage erforderlich und werden nicht an Dritte weitergegeben. Diese Einwilligung kann ich jederzeit mit Wirkung f\u00fcr die Zukunft durch Mitteilung an Netzband &amp; Mederos widerrufen.<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-8f32c5e9 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-786700b4\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8ebaca60\"><h3 class=\"uagb-heading-text\"><mark class=\"uagb-highlight\">Kontakt<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-1f68fa19 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path d=\"M168.3 499.2C116.1 435 0 279.4 0 192C0 85.96 85.96 0 192 0C298 0 384 85.96 384 192C384 279.4 267 435 215.7 499.2C203.4 514.5 180.6 514.5 168.3 499.2H168.3zM192 256C227.3 256 256 227.3 256 192C256 156.7 227.3 128 192 128C156.7 128 128 156.7 128 192C128 227.3 156.7 256 192 256z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title\">B\u00fcro adresse:<\/h6><\/div><p class=\"uagb-ifb-desc\">Avda. Moya, n\u00ba 6<br>Centro Comercial Eurocenter,<br>local 201 &#8211; 211<br>\u200b<br>E-35100 Playa del Ingles<br>Islas Canarias, Espa\u00f1a<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-989369dc uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M511.2 387l-23.25 100.8c-3.266 14.25-15.79 24.22-30.46 24.22C205.2 512 0 306.8 0 54.5c0-14.66 9.969-27.2 24.22-30.45l100.8-23.25C139.7-2.602 154.7 5.018 160.8 18.92l46.52 108.5c5.438 12.78 1.77 27.67-8.98 36.45L144.5 207.1c33.98 69.22 90.26 125.5 159.5 159.5l44.08-53.8c8.688-10.78 23.69-14.51 36.47-8.975l108.5 46.51C506.1 357.2 514.6 372.4 511.2 387z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title\">Telefonnummer:<\/h6><\/div><p class=\"uagb-ifb-desc\">(+34) 928768280<br>(+34) 669859007<br>(+34) 629079765<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-ab49ed9c uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M464 64C490.5 64 512 85.49 512 112C512 127.1 504.9 141.3 492.8 150.4L275.2 313.6C263.8 322.1 248.2 322.1 236.8 313.6L19.2 150.4C7.113 141.3 0 127.1 0 112C0 85.49 21.49 64 48 64H464zM217.6 339.2C240.4 356.3 271.6 356.3 294.4 339.2L512 176V384C512 419.3 483.3 448 448 448H64C28.65 448 0 419.3 0 384V176L217.6 339.2z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title\">E-Mail:<\/h6><\/div><p class=\"uagb-ifb-desc\">info@mederos-netzband.com<br>info@netzband-mederos.com<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-df38fd15\">\n<div class=\"wp-block-uagb-image uagb-block-bb583529 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none uag-blocks-common-selector\" style=\"--z-index-desktop:999;;--z-index-tablet:undefined;;--z-index-mobile:undefined;\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/10\/contact-img4.png ,https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/10\/contact-img4.png 780w, https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/10\/contact-img4.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/10\/contact-img4.png\" alt=\"\" class=\"uag-image-637\" width=\"350\" height=\"530\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-b03da732\">\n<h3 class=\"wp-block-heading has-text-align-center\" style=\"margin-top:0;margin-bottom:0\">In Kontakt kommen !<\/h3>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f169-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"169\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/133#wpcf7-f169-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/de\/wp-json\/wp\/v2\/pages\/133#wpcf7-f169-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"169\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.3\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f169-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"uacf7-form-wrapper-container uacf7-form-169\"><label style=\"color: black;\"> Ihr Name*\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n\n<label style=\"color: black;\"> Deine E-Mail*\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n\n<label style=\"color: black;\"> Aff\u00e4re*\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n\n<label style=\"color: black;\"> Telefon*\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"your-phone\" \/><\/span> <\/label>\n\n<label style=\"color: black;\"> Ihre Nachricht\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n\n\n\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Schicken\" \/><\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"de\"\/><\/form>\n<\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center has-secondary-accent-text-color has-text-color has-link-color has-x-small-font-size wp-elements-27674763fc62a6e6170b1f6a8dfb8d92\">Hiermit erkl\u00e4re ich mein Einverst\u00e4ndnis zur Verarbeitung meiner Daten. Die Daten sind zur Bearbeitung meiner Kontaktanfrage erforderlich und werden nicht an Dritte weitergegeben. Diese Einwilligung kann ich jederzeit mit Wirkung f\u00fcr die Zukunft durch Mitteilung an Netzband &amp; Mederos widerrufen.<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-08c85f05 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-bb263e33 wp-block-group-is-layout-constrained\" style=\"border-radius:30px;min-height:0px;margin-top:var(--wp--preset--spacing--small);margin-bottom:var(--wp--preset--spacing--small);padding-bottom:var(--wp--preset--spacing--xx-small)\"><\/div>\n\n\n\t\t\t<div \n\t\t\tclass=\"wp-block-uagb-google-map uagb-google-map__wrap uagb-block-1a6e70e1\"\n\t\t\tstyle=\"\" >\n\t\t\t\t<embed\n\t\t\t\t\tclass=\"uagb-google-map__iframe\"\n\t\t\t\t\ttitle=\"Google Map for \"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=27.764979801454942%2C%20-15.571156741641628&#038;z=16&#038;hl=es&#038;t=m&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\twidth=\"640\"\n\t\t\t\t\theight=\"300\"\n\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t><\/embed>\n\t\t\t<\/div>\n\t\t\t<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a1BIENVENIDO A LA SOLUCI\u00d3N! Nuestra experiencia de equipo legal de + de 25 a\u00f1os, es tu ventaja SERVICIOS ESPECIALIZADOS PARA TI Despacho local trabajando a nivel internacional. \u00bfNecesitas asesoramiento legal con abogados en espa\u00f1ol o en Alem\u00e1n? LA FILOSOF\u00cdA DE NUESTRO&nbsp;DESPACHO +25 A\u00d1OS \u00c9XITO JUDICIAL Judicial ExtraJudicial Socios fundadores WOLFRAM&nbsp;&nbsp;NETZBAND SOCIO FUNDADOR Abogado ELSA MEDEROS [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width","meta":{"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-133","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>INICIO - NETZBAND &amp; MEDEROS<\/title>\n<meta name=\"description\" content=\"Buscamos la mejor defensa de nuestros clientes, utilizando el conocimiento de los dos sistemas de derecho, espa\u00f1ol y alem\u00e1n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mederos-netzband.com\/de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INICIO - NETZBAND &amp; MEDEROS\" \/>\n<meta property=\"og:description\" content=\"Buscamos la mejor defensa de nuestros clientes, utilizando el conocimiento de los dos sistemas de derecho, espa\u00f1ol y alem\u00e1n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mederos-netzband.com\/de\/\" \/>\n<meta property=\"og:site_name\" content=\"NETZBAND &amp; MEDEROS\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-03T14:13:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4174-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mederos-netzband.com\/\",\"url\":\"https:\/\/mederos-netzband.com\/\",\"name\":\"INICIO - NETZBAND &amp; MEDEROS\",\"isPartOf\":{\"@id\":\"https:\/\/mederos-netzband.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mederos-netzband.com\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mederos-netzband.com\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4174-scaled.jpg\",\"datePublished\":\"2023-10-04T08:53:13+00:00\",\"dateModified\":\"2025-11-03T14:13:31+00:00\",\"description\":\"Buscamos la mejor defensa de nuestros clientes, utilizando el conocimiento de los dos sistemas de derecho, espa\u00f1ol y alem\u00e1n\",\"breadcrumb\":{\"@id\":\"https:\/\/mederos-netzband.com\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mederos-netzband.com\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/mederos-netzband.com\/#primaryimage\",\"url\":\"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4174-scaled.jpg\",\"contentUrl\":\"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4174-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mederos-netzband.com\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"inicio\",\"item\":\"https:\/\/mederos-netzband.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"inicio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mederos-netzband.com\/#website\",\"url\":\"https:\/\/mederos-netzband.com\/\",\"name\":\"NETZBAND & MEDEROS\",\"description\":\"Despacho de abogados internacional\",\"publisher\":{\"@id\":\"https:\/\/mederos-netzband.com\/#organization\"},\"alternateName\":\"MEDEROS & NETZBAND\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mederos-netzband.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mederos-netzband.com\/#organization\",\"name\":\"NETZBAND & MEDEROS\",\"alternateName\":\"MEDEROS & NETZBAND\",\"url\":\"https:\/\/mederos-netzband.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/mederos-netzband.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/11\/logo_netzband.png\",\"contentUrl\":\"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/11\/logo_netzband.png\",\"width\":1777,\"height\":248,\"caption\":\"NETZBAND & MEDEROS\"},\"image\":{\"@id\":\"https:\/\/mederos-netzband.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INICIO - NETZBAND &amp; MEDEROS","description":"Buscamos la mejor defensa de nuestros clientes, utilizando el conocimiento de los dos sistemas de derecho, espa\u00f1ol y alem\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mederos-netzband.com\/de\/","og_locale":"de_DE","og_type":"article","og_title":"INICIO - NETZBAND &amp; MEDEROS","og_description":"Buscamos la mejor defensa de nuestros clientes, utilizando el conocimiento de los dos sistemas de derecho, espa\u00f1ol y alem\u00e1n","og_url":"https:\/\/mederos-netzband.com\/de\/","og_site_name":"NETZBAND &amp; MEDEROS","article_modified_time":"2025-11-03T14:13:31+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4174-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mederos-netzband.com\/","url":"https:\/\/mederos-netzband.com\/","name":"INICIO - NETZBAND &amp; MEDEROS","isPartOf":{"@id":"https:\/\/mederos-netzband.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mederos-netzband.com\/#primaryimage"},"image":{"@id":"https:\/\/mederos-netzband.com\/#primaryimage"},"thumbnailUrl":"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4174-scaled.jpg","datePublished":"2023-10-04T08:53:13+00:00","dateModified":"2025-11-03T14:13:31+00:00","description":"Buscamos la mejor defensa de nuestros clientes, utilizando el conocimiento de los dos sistemas de derecho, espa\u00f1ol y alem\u00e1n","breadcrumb":{"@id":"https:\/\/mederos-netzband.com\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mederos-netzband.com\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mederos-netzband.com\/#primaryimage","url":"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4174-scaled.jpg","contentUrl":"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/12\/IMG_4174-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/mederos-netzband.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"inicio","item":"https:\/\/mederos-netzband.com\/"},{"@type":"ListItem","position":2,"name":"inicio"}]},{"@type":"WebSite","@id":"https:\/\/mederos-netzband.com\/#website","url":"https:\/\/mederos-netzband.com\/","name":"NETZBAND & MEDEROS","description":"Despacho de abogados internacional","publisher":{"@id":"https:\/\/mederos-netzband.com\/#organization"},"alternateName":"MEDEROS & NETZBAND","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mederos-netzband.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mederos-netzband.com\/#organization","name":"NETZBAND & MEDEROS","alternateName":"MEDEROS & NETZBAND","url":"https:\/\/mederos-netzband.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mederos-netzband.com\/#\/schema\/logo\/image\/","url":"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/11\/logo_netzband.png","contentUrl":"https:\/\/mederos-netzband.com\/wp-content\/uploads\/2023\/11\/logo_netzband.png","width":1777,"height":248,"caption":"NETZBAND & MEDEROS"},"image":{"@id":"https:\/\/mederos-netzband.com\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/mederos-netzband.com\/de\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00a1BIENVENIDO A LA SOLUCI\u00d3N! Nuestra experiencia de equipo legal de + de 25 a\u00f1os, es tu ventaja SERVICIOS ESPECIALIZADOS PARA TI Despacho local trabajando a nivel internacional. \u00bfNecesitas asesoramiento legal con abogados en espa\u00f1ol o en Alem\u00e1n? LA FILOSOF\u00cdA DE NUESTRO&nbsp;DESPACHO +25 A\u00d1OS \u00c9XITO JUDICIAL Judicial ExtraJudicial Socios fundadores WOLFRAM&nbsp;&nbsp;NETZBAND SOCIO FUNDADOR Abogado ELSA MEDEROS&hellip;","_links":{"self":[{"href":"https:\/\/mederos-netzband.com\/de\/wp-json\/wp\/v2\/pages\/133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mederos-netzband.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mederos-netzband.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mederos-netzband.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mederos-netzband.com\/de\/wp-json\/wp\/v2\/comments?post=133"}],"version-history":[{"count":81,"href":"https:\/\/mederos-netzband.com\/de\/wp-json\/wp\/v2\/pages\/133\/revisions"}],"predecessor-version":[{"id":819,"href":"https:\/\/mederos-netzband.com\/de\/wp-json\/wp\/v2\/pages\/133\/revisions\/819"}],"wp:attachment":[{"href":"https:\/\/mederos-netzband.com\/de\/wp-json\/wp\/v2\/media?parent=133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}